{"id":1205,"date":"2016-11-15T09:47:22","date_gmt":"2016-11-15T08:47:22","guid":{"rendered":"http:\/\/www.picuida.es\/ciudadania\/?p=1205"},"modified":"2020-03-10T11:27:14","modified_gmt":"2020-03-10T10:27:14","slug":"complejo-hospitalario-jaen-impartira-talleres-ayudar-los-pacientes-enfermedades-hematologicas-familiares","status":"publish","type":"post","link":"https:\/\/www.picuida.es\/ciudadania\/complejo-hospitalario-jaen-impartira-talleres-ayudar-los-pacientes-enfermedades-hematologicas-familiares\/","title":{"rendered":"El Complejo Hospitalario de Ja\u00e9n impartir\u00e1 talleres para ayudar a los pacientes con enfermedades hematol\u00f3gicas y sus familiares"},"content":{"rendered":"<p style=\"text-align: justify;\">Profesionales del Complejo Hospitalario de Ja\u00e9n impartir\u00e1n el pr\u00f3ximo martes 22 de noviembre su segundo taller para pacientes con enfermedades hematol\u00f3gicas y sus familiares, donde expondr\u00e1n sus necesidades y recibir\u00e1n soluciones y consejos para mejorar la atenci\u00f3n sanitaria que se les presta y su estado de salud.<\/p>\n<p style=\"text-align: justify;\">Esta \u00abEscuela de Pacientes\u00bb est\u00e1 destinada a todos aquellos interesados en conocer las enfermedades hematol\u00f3gicas. Pretende ser un lugar de encuentro para compartir experiencias y conocimientos. Su objetivo principal es el desarrollo de actividades de ayuda, informaci\u00f3n y formaci\u00f3n sobre los trastornos que afectan a la sangre y a sus tratamientos, as\u00ed como el dise\u00f1o de actividades que respondan a las necesidades de pacientes y familiares.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.sas.junta-andalucia.es\/principal\/noticia.asp?codcontenido=27457&amp;utm_source=servicioandaluzdesalud&amp;utm_campaign=Boletin%20Novedades&amp;utm_medium=mail&amp;utm_content=20161114&amp;utm_term=El%20Complejo%20Hospitalario%20de%20Jaen%20impartira%20su%20segundo%20taller%20para%20ayudar%20a%20los%20pacientes%20con%20enfermedades%20hematologicas%20y%20sus%20familiares\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"size-medium wp-image-1206 aligncenter\" src=\"http:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/11\/20161114_iag955p4_2_b-300x225.png\" alt=\"20161114_iag955p4_2_b\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/11\/20161114_iag955p4_2_b-300x225.png 300w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/11\/20161114_iag955p4_2_b.png 320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Este encuentro incluir\u00e1 varias charlas de expertos en esta patolog\u00eda y concluir\u00e1 con un coloquio donde lo asistentes expondr\u00e1n distintas cuestiones y todas sus dudas, que responder\u00e1n los profesionales sanitarios de esta unidad de gesti\u00f3n cl\u00ednica del hospital p\u00fablico de la capital jiennense.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.sas.junta-andalucia.es\/principal\/noticia.asp?codcontenido=27457&amp;utm_source=servicioandaluzdesalud&amp;utm_campaign=Boletin%20Novedades&amp;utm_medium=mail&amp;utm_content=20161114&amp;utm_term=El%20Complejo%20Hospitalario%20de%20Jaen%20impartira%20su%20segundo%20taller%20para%20ayudar%20a%20los%20pacientes%20con%20enfermedades%20hematologicas%20y%20sus%20familiares\" target=\"_blank\" rel=\"noopener noreferrer\">SAS<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profesionales del Complejo Hospitalario de Ja\u00e9n impartir\u00e1n el pr\u00f3ximo martes 22 de noviembre su segundo taller para pacientes con enfermedades hematol\u00f3gicas y sus familiares, donde [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_featured_media_url":"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/11\/20161114_iag955p4_2_b.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/1205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":1,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/1205\/revisions"}],"predecessor-version":[{"id":3496,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/1205\/revisions\/3496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media\/1206"}],"wp:attachment":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media?parent=1205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/categories?post=1205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/tags?post=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}