{"id":1538,"date":"2017-02-22T23:12:32","date_gmt":"2017-02-22T22:12:32","guid":{"rendered":"http:\/\/www.picuida.es\/ciudadania\/?p=1538"},"modified":"2017-02-22T23:12:32","modified_gmt":"2017-02-22T22:12:32","slug":"preguntas-respuestas-la-osteoporosis","status":"publish","type":"post","link":"https:\/\/www.picuida.es\/ciudadania\/preguntas-respuestas-la-osteoporosis\/","title":{"rendered":"Preguntas y respuestas sobre la osteoporosis"},"content":{"rendered":"<p style=\"text-align: justify;\">La osteoporosis es una enfermedad de los huesos\u00a0en la que se produce una disminuci\u00f3n de la densidad de masa \u00f3sea. As\u00ed, los huesos se vuelven m\u00e1s porosos, aumenta el n\u00famero y el tama\u00f1o de las cavidades o celdillas que existen en su interior, son m\u00e1s fr\u00e1giles, resisten peor los golpes y se rompen con mayor facilidad.<\/p>\n<p style=\"text-align: justify;\">La osteoporosis no manifiesta s\u00edntomas hasta que la p\u00e9rdida de hueso es tan importante como para que aparezcan fracturas. Las fracturas m\u00e1s frecuentes son las vertebrales, las de cadera y las de la mu\u00f1eca. La fractura de cadera tiene especial importancia ya que se considera un acontecimiento grave debido a que requiere intervenci\u00f3n quir\u00fargica, ingreso hospitalario y supone para el paciente una p\u00e9rdida de calidad de vida aunque sea por un periodo corto de tiempo.<\/p>\n<p style=\"text-align: justify;\">Esta enfermedad afecta principalmente a mujeres despu\u00e9s de la menopausia aunque tambi\u00e9n puede hacerlo antes o afectar a hombres, adolescentes e incluso ni\u00f1os. En concreto, en Espa\u00f1a, aproximadamente 2 millones de mujeres padecen osteoporosis. Se estima que esta enfermedad es la causante de unas 25.000 fracturas cada a\u00f1o. Aproximadamente 1 de cada 3 mujeres y 1 de cada 5 hombres mayores de 50 a\u00f1os sufrir\u00e1 una fractura osteopor\u00f3tica en su vida.<\/p>\n<p style=\"text-align: justify;\">Para conocer m\u00e1s sobre la osteoporosis puedes encontrar m\u00e1s informaci\u00f3n en esta <a href=\"https:\/\/www.msdsalud.es\/cuidar-en\/osteoporosis\/quieres-saber-mas\/50-preguntas-respuestas-comunes-osteoporosis.html\" target=\"_blank\" rel=\"noopener\">web (50 preguntas y respuestas comunes sobre la osteoporosis).<\/a> Esta informaci\u00f3n est\u00e1 avalada por la <a href=\"http:\/\/www.aecos.es\/\" target=\"_blank\" rel=\"noopener\">Asociaci\u00f3n Espa\u00f1ola con la osteoporosis y la artrosis<\/a> y la <a href=\"http:\/\/www.fhoemo.com\/\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n Hispana de Osteoporosis y Enfermedades Metab\u00f3licas \u00d3seas.<\/a><\/p>\n<p>Compartimos tambi\u00e9n una serie de documentos de gran inter\u00e9s para saber m\u00e1s sobre la osteoporosis.<\/p>\n<p><a href=\"http:\/\/www.fhoemo.com\/wp-content\/uploads\/2014\/06\/Osteoporosis.-Que-no-te-rompa-la-vida.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"size-medium wp-image-1544 aligncenter\" src=\"http:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis-223x300.jpg\" alt=\"\" width=\"223\" height=\"300\" srcset=\"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis-223x300.jpg 223w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis.jpg 685w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.fhoemo.com\/wp-content\/uploads\/2014\/06\/Consejos-para-evitar-las-caidas.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"size-medium wp-image-1545 aligncenter\" src=\"http:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis1-173x300.jpg\" alt=\"\" width=\"173\" height=\"300\" srcset=\"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis1-173x300.jpg 173w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis1-590x1024.jpg 590w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis1.jpg 591w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.fhoemo.com\/wp-content\/uploads\/2014\/06\/Recomendaciones-de-la-OMS-y-la-IOF-para-el-paciente.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"size-medium wp-image-1546 aligncenter\" src=\"http:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis2-300x210.jpg\" alt=\"\" width=\"300\" height=\"210\" srcset=\"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis2-300x210.jpg 300w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis2-768x537.jpg 768w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis2-1024x717.jpg 1024w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis2.jpg 1239w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La osteoporosis es una enfermedad de los huesos\u00a0en la que se produce una disminuci\u00f3n de la densidad de masa \u00f3sea. As\u00ed, los huesos se vuelven [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[136],"class_list":["post-1538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conociendo-mi-enfermedad","tag-osteoporosis"],"jetpack_featured_media_url":"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2017\/02\/osteoporosis.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/1538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/comments?post=1538"}],"version-history":[{"count":0,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/1538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media\/1544"}],"wp:attachment":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media?parent=1538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/categories?post=1538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/tags?post=1538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}