{"id":571,"date":"2016-06-17T18:57:49","date_gmt":"2016-06-17T18:57:49","guid":{"rendered":"http:\/\/www.picuida.es\/ciudadania\/?p=571"},"modified":"2016-07-08T09:55:44","modified_gmt":"2016-07-08T07:55:44","slug":"guia-de-nutricion-para-personas-con-disfagia","status":"publish","type":"post","link":"https:\/\/www.picuida.es\/ciudadania\/guia-de-nutricion-para-personas-con-disfagia\/","title":{"rendered":"Gu\u00eda de Nutrici\u00f3n para personas con disfagia"},"content":{"rendered":"<p style=\"text-align: justify;\">La disfagia es la alteraci\u00f3n o dificultad en el proceso de la degluci\u00f3n. Las personas que padecen disfagia, pueden tener alterada la eficacia de la degluci\u00f3n, y por lo tanto, la\u00a0capacidad para alimentarse e hidratarse de manera \u00f3ptima,<\/p>\n<p style=\"text-align: justify;\">En esta <a href=\"http:\/\/www.imserso.es\/InterPresent1\/groups\/imserso\/documents\/binario\/600077_guia_nutricion_disfagia.pdf\" target=\"_blank\" rel=\"noopener\">gu\u00eda<\/a>\u00a0editada por el Ministerio de Sanidad, Servicios Sociales e Igualdad, se re\u00fanen conceptos cl\u00ednicos sencillos sobre este s\u00edntoma y aspectos nutricionales b\u00e1sicos para estructurar una dieta, incluyendo recomendaciones pr\u00e1cticas sobre consistencias y texturas, pautas durante la alimentaci\u00f3n, alimentos recomendados y a evitar, ajuste de calor\u00edas y nutrientes y variedad en la alimentaci\u00f3n para que sea aceptada por el paciente.<\/p>\n<p><a href=\"http:\/\/www.imserso.es\/InterPresent1\/groups\/imserso\/documents\/binario\/600077_guia_nutricion_disfagia.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"size-medium wp-image-572 aligncenter\" src=\"http:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/guia-disfagia-300x224.png\" alt=\"guia disfagia\" width=\"300\" height=\"224\" srcset=\"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/guia-disfagia-300x224.png 300w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/guia-disfagia-768x573.png 768w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/guia-disfagia.png 896w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La disfagia es la alteraci\u00f3n o dificultad en el proceso de la degluci\u00f3n. Las personas que padecen disfagia, pueden tener alterada la eficacia de la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[62,14],"class_list":["post-571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conociendo-mi-enfermedad","tag-disfagia","tag-guias"],"jetpack_featured_media_url":"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/guiadisfagia.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/comments?post=571"}],"version-history":[{"count":0,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media\/746"}],"wp:attachment":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media?parent=571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/categories?post=571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/tags?post=571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}