{"id":614,"date":"2016-07-07T09:00:03","date_gmt":"2016-07-07T07:00:03","guid":{"rendered":"http:\/\/www.picuida.es\/ciudadania\/?p=614"},"modified":"2020-03-10T11:13:29","modified_gmt":"2020-03-10T10:13:29","slug":"cuentos-infantiles-sobre-epilepsia","status":"publish","type":"post","link":"https:\/\/www.picuida.es\/ciudadania\/cuentos-infantiles-sobre-epilepsia\/","title":{"rendered":"Cuentos Infantiles sobre Epilepsia"},"content":{"rendered":"<p style=\"text-align: justify;\">En Espa\u00f1a, la epilepsia afecta a unos 400.000 espa\u00f1oles, y de los nuevos casos que se detectan, el 40 por ciento son en menores de 15 a\u00f1os, aunque la mayor parte de casos de epilepsia infantil tienen buena evoluci\u00f3n y obedecen al tratamiento.<\/p>\n<p style=\"text-align: justify;\">Con el objetivo de acercar esta enfermedad a los ni\u00f1os, tanto los que la sufren como los que no, la neuropediatra Patricia Smeyers de la Unidad de Epilepsia del Hospital La Fe de Valencia y con\u00a0la colaboraci\u00f3n de la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN), decidi\u00f3 escribir una serie de cuentos, historias divertidas, que abordan la enfermedad y la acercan a los m\u00e1s peque\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Puedes encontrarlos en la web de <a href=\"http:\/\/vivirconepilepsia.es\/epilepsia-infantil\/cuentos-infantiles-sobre-epilepsia\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vivir con Epilepsia<\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/vivirconepilepsia.es\/epilepsia-infantil\/cuentos-infantiles-sobre-epilepsia\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"size-medium wp-image-615 aligncenter\" src=\"http:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/LaPocimaAusencias-300x300.jpg\" alt=\"LaPocimaAusencias\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/LaPocimaAusencias-150x150.jpg 150w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/LaPocimaAusencias-300x300.jpg 300w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/LaPocimaAusencias-325x325.jpg 325w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/LaPocimaAusencias.jpg 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Espa\u00f1a, la epilepsia afecta a unos 400.000 espa\u00f1oles, y de los nuevos casos que se detectan, el 40 por ciento son en menores de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[210,70,15,178],"class_list":["post-614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conociendo-mi-enfermedad","tag-dia-universal-del-nino","tag-epilepsia","tag-folletos","tag-vuelta-al-cole"],"jetpack_featured_media_url":"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/06\/LaPocimaAusencias.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/comments?post=614"}],"version-history":[{"count":1,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/614\/revisions"}],"predecessor-version":[{"id":3483,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/614\/revisions\/3483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media\/615"}],"wp:attachment":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media?parent=614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/categories?post=614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/tags?post=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}