{"id":782,"date":"2016-07-18T08:45:40","date_gmt":"2016-07-18T06:45:40","guid":{"rendered":"http:\/\/www.picuida.es\/ciudadania\/?p=782"},"modified":"2020-10-14T11:40:23","modified_gmt":"2020-10-14T09:40:23","slug":"apuesta-por-un-uso-responsable-de-las-tic-educar-para-proteger","status":"publish","type":"post","link":"https:\/\/www.picuida.es\/ciudadania\/apuesta-por-un-uso-responsable-de-las-tic-educar-para-proteger\/","title":{"rendered":"Uso responsable de las TIC: educar para proteger"},"content":{"rendered":"<p style=\"text-align: justify;\">Las nuevas aplicaciones para los dispositivos m\u00f3viles comienzan a tomar conciencia de la importancia de un uso responsable de las nuevas tecnolog\u00edas, algo fundamental en la relaci\u00f3n de nuestros hijos con las TICs y que, en gran medida, es responsabilidad de los padres.<\/p>\n<p style=\"text-align: justify;\">Un ejemplo es <a href=\"http:\/\/www.blog.andaluciaesdigital.es\/youtube-kids-guia-para-aprender-a-configurarlo\/\" target=\"_blank\" rel=\"noopener\">YouTube Kids<\/a>, el famoso reproductor de v\u00eddeos online que acaba de sacar una versi\u00f3n para los m\u00e1s peque\u00f1os de la casa y donde la <strong>opci\u00f3n de control parental<\/strong> est\u00e1 muy presente. Los padres pueden configurar las opciones para limitar tanto las b\u00fasquedas de v\u00eddeos, como marcar aquellos de contenido inapropiado y el tiempo en la que la aplicaci\u00f3n estar\u00e1 activa y decidir cu\u00e1nto tiempo es el adecuado para estar visionando v\u00eddeos.<\/p>\n<p style=\"text-align: justify;\">Tanto para padres como para hijos, la Junta de Andaluc\u00eda pone a disposici\u00f3n las <a href=\"http:\/\/www.andaluciaesdigital.es\/colectivo\/familias-y-educadores\/educar-para-proteger\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Gu\u00edas Educar para Proteger<\/strong><\/a> que ofrecen claves y consejos adaptados a todas las edades.<\/p>\n<p style=\"text-align: justify;\">Junto a ellas, y para dar los primeros pasos con las nuevas tecnolog\u00edas y aprender conceptos b\u00e1sics de seguridad mientras se juegan, el <a href=\"http:\/\/www.andaluciaesdigital.es\/colectivo\/familias-y-educadores\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>espacio para familias y educadores de Andaluc\u00eda es Digital<\/strong><\/a> te ofrece juegos y aplicaciones adaptados a todas las edades para que comiencen a familiarizarse con las TIC. \u00a1Vis\u00edtalo!<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-medium wp-image-786 aligncenter\" src=\"http:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/07\/Youtube_kids_2-300x158.jpg\" alt=\"Youtube_kids_2\" width=\"300\" height=\"158\" srcset=\"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/07\/Youtube_kids_2-300x158.jpg 300w, https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/07\/Youtube_kids_2.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las nuevas aplicaciones para los dispositivos m\u00f3viles comienzan a tomar conciencia de la importancia de un uso responsable de las nuevas tecnolog\u00edas, algo fundamental en [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_featured_media_url":"https:\/\/www.picuida.es\/ciudadania\/wp-content\/uploads\/2016\/07\/Youtube_kids_2.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":2,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":3787,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/posts\/782\/revisions\/3787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media\/786"}],"wp:attachment":[{"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picuida.es\/ciudadania\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}